{"id":3359,"date":"2017-01-08T16:50:03","date_gmt":"2017-01-09T00:50:03","guid":{"rendered":"\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg"},"modified":"2017-01-08T17:03:46","modified_gmt":"2017-01-09T01:03:46","slug":"estes","status":"inherit","type":"attachment","link":"https:\/\/depts.washington.edu\/uwautism\/research-team\/estes\/#main","title":{"rendered":"estes"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"class_list":["post-3359","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>estes - UW Autism<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"estes - UW Autism\" \/>\n<meta property=\"og:url\" content=\"\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg\" \/>\n<meta property=\"og:site_name\" content=\"UW Autism\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-09T01:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"65\" \/>\n\t<meta property=\"og:image:height\" content=\"65\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"\\\/uwautism\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/estes.jpg\",\"url\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/estes.jpg\",\"name\":\"estes - UW Autism\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/#website\"},\"datePublished\":\"2017-01-09T00:50:03+00:00\",\"dateModified\":\"2017-01-09T01:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/estes.jpg#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/estes.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/estes.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/depts.washington.edu\\\/uwautism\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research Network\",\"item\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/research-team\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"estes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/#website\",\"url\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/\",\"name\":\"UW Autism\",\"description\":\"University of Washington\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/depts.washington.edu\\\/uwautism\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"estes - UW Autism","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg","og_locale":"en_US","og_type":"article","og_title":"estes - UW Autism","og_url":"\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg","og_site_name":"UW Autism","article_modified_time":"2017-01-09T01:03:46+00:00","og_image":[{"width":65,"height":65,"url":"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg","url":"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg","name":"estes - UW Autism","isPartOf":{"@id":"https:\/\/depts.washington.edu\/uwautism\/#website"},"datePublished":"2017-01-09T00:50:03+00:00","dateModified":"2017-01-09T01:03:46+00:00","breadcrumb":{"@id":"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/depts.washington.edu\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/depts.washington.edu\/uwautism\/"},{"@type":"ListItem","position":2,"name":"Research Network","item":"https:\/\/depts.washington.edu\/uwautism\/research-team\/"},{"@type":"ListItem","position":3,"name":"estes"}]},{"@type":"WebSite","@id":"https:\/\/depts.washington.edu\/uwautism\/#website","url":"https:\/\/depts.washington.edu\/uwautism\/","name":"UW Autism","description":"University of Washington","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/depts.washington.edu\/uwautism\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg'><img decoding=\"async\" width=\"65\" height=\"65\" src=\"\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":65,"height":65,"file":"2017\/01\/estes.jpg","filesize":22676,"sizes":{},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1483891026","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":1577,"source_url":"\/uwautism\/wp-content\/uploads\/2017\/01\/estes.jpg","_links":{"self":[{"href":"https:\/\/depts.washington.edu\/uwautism\/wp-json\/wp\/v2\/media\/3359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/depts.washington.edu\/uwautism\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/depts.washington.edu\/uwautism\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/depts.washington.edu\/uwautism\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/depts.washington.edu\/uwautism\/wp-json\/wp\/v2\/comments?post=3359"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":1577,"href":"https:\/\/depts.washington.edu\/uwautism\/wp-json\/wp\/v2\/pages\/1577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}